{"id":8715,"date":"2025-01-23T16:08:24","date_gmt":"2025-01-23T15:08:24","guid":{"rendered":"https:\/\/fonakeukeu.org\/?page_id=8715"},"modified":"2025-04-04T13:30:19","modified_gmt":"2025-04-04T11:30:19","slug":"actualites-2","status":"publish","type":"page","link":"https:\/\/fonakeukeu.org\/en\/actualites-2\/","title":{"rendered":"Actualit\u00e9s"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8715\" class=\"elementor elementor-8715\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d153511 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d153511\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3850b92\" data-id=\"3850b92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed3b4d0 elementor-widget-laptop__width-initial elementor-widget elementor-widget-ucaddon_post_blocks\" data-id=\"ed3b4d0\" data-element_type=\"widget\" data-widget_type=\"ucaddon_post_blocks.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Post Blocks -->\n\t\t<link id='font-awesome-css' href='https:\/\/fonakeukeu.org\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/fonakeukeu.org\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-v4-shims.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Post Blocks *\/\n\n\n\n#uc_post_blocks_elementor_ed3b4d0 {\n    display:grid;\n}\n#uc_post_blocks_elementor_ed3b4d0 .ue_post_blocks_box\n{\n  overflow:hidden;\n}\n\n#uc_post_blocks_elementor_ed3b4d0 .ue_post_blocks_image\n{\n  overflow:hidden;\n}\n#uc_post_blocks_elementor_ed3b4d0 .ue_post_blocks_image img\n{\n  width:100%;\n  display:block;\n}\n#uc_post_blocks_elementor_ed3b4d0 .ue_post_blocks_link a\n{\n  display:inline-block;\n  text-decoration:none;\n  text-align:center;\n}\n\n\n#uc_post_blocks_elementor_ed3b4d0 .ue-grid-item-meta-data\n{\n  display:inlin-flex;\n  flex-wrap: wrap;\n}\n\n.ue-grid-item-meta-data\n{\n  font-size:12px;\n}\n\n#uc_post_blocks_elementor_ed3b4d0 .ue-grid-item-meta-data-icon\n{\n  line-height:1em;\n}\n\n#uc_post_blocks_elementor_ed3b4d0 .ue-grid-item-meta-data-icon svg\n{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_blocks_elementor_ed3b4d0 .ue_post_blocks_box{\n  display: flex;\n  flex-direction: column;\n}\n#uc_post_blocks_elementor_ed3b4d0 .ue_post_blocks_content{\n display: flex; flex-grow: 1;\n flex-direction: column;\n}\n#uc_post_blocks_elementor_ed3b4d0 .ue_post_blocks_link{ margin-top: auto;\n}\n\n.ue-grid-item-category a\n{\n  display:inline-block;\n  font-size:10px;\n  text-transform:uppercase;\n}\n\n\n\n\n<\/style>\n\n\t\t\t<div id=\"uc_post_blocks_elementor_ed3b4d0\" class=\"ue_post_blocks uc-items-wrapper\" >\n    <div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2026\/02\/17\/fete-de-la-jeunesse-2026\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-17-at-4.30.27-AM-768x576.jpeg\"  alt=\"WhatsApp Image 2026-02-17 at 4.30\" width=\"768\" height=\"576\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2026\/02\/17\/fete-de-la-jeunesse-2026\/\">F\u00eate de la jeunesse 2026<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\"><\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2026\/02\/17\/fete-de-la-jeunesse-2026\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/09\/08\/rapport-de-la-derniere-reunion-de-ladf\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/09\/IMG-20250908-WA0013.jpg\"  alt=\"IMG-20250908-WA0013\" width=\"636\" height=\"900\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/09\/08\/rapport-de-la-derniere-reunion-de-ladf\/\">Rapport de la derni\u00e8re r\u00e9union de l'adf<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Bonsoir cher membre du d\u00e9veloppement fona, Je tiens particuli\u00e8rement \u00e0 te faire lire le rapport de la...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/09\/08\/rapport-de-la-derniere-reunion-de-ladf\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/07\/11\/festival-yemba-canada-2025-le-parc-angrignon-transforme-en-village-royal\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-11-090651-768x437.png\"  alt=\"Capture d&#039;\u00e9cran 2025-07-11 090651\" width=\"768\" height=\"437\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/07\/11\/festival-yemba-canada-2025-le-parc-angrignon-transforme-en-village-royal\/\">Festival Yemba Canada 2025 : Le parc Angrignon transform\u00e9 en village royal<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\"><\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/07\/11\/festival-yemba-canada-2025-le-parc-angrignon-transforme-en-village-royal\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/07\/11\/festival-yemba-canada-2025\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-11-085308.png\"  alt=\"Capture d&#039;\u00e9cran 2025-07-11 085308\" width=\"760\" height=\"430\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/07\/11\/festival-yemba-canada-2025\/\">Festival Yemba Canada 2025<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Le Festival Yemba Canada 2025 vous invite \u00e0 une journ\u00e9e exceptionnelle plac\u00e9e sous le signe de l\u2019authenticit\u00e9...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/07\/11\/festival-yemba-canada-2025\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/06\/30\/association-yemba\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-30-a-11.19.19_47368cd2-768x543.jpg\"  alt=\"WhatsApp Image 2025-06-30 \u00e0 11.19\" width=\"768\" height=\"543\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><a href=\"https:\/\/fonakeukeu.org\/en\/category\/communiques\/\">Communiqu\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/06\/30\/association-yemba\/\">Association yemba<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">\u00c9changes entre les professionnels de l&rsquo;\u00e9ducation d&rsquo;ici et d&rsquo;ailleurs: Cameroun\u00a0et\u00a0Canada<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/06\/30\/association-yemba\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/06\/06\/entretien-des-routes-pari-tsu\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/06\/v1-768x1152.jpg\"  alt=\"v1\" width=\"768\" height=\"1152\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/06\/06\/entretien-des-routes-pari-tsu\/\">Entretien\u00a0des\u00a0routes PARI TSU!<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\"><\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/06\/06\/entretien-des-routes-pari-tsu\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/remise-des-prix-de-lexcellence-scolaire-aux-trois-premiers-de-chaque-classe-du-lycee\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-03-03-a-12.47.40_2ac4be7a-768x576.jpg\"  alt=\"WhatsApp Image 2025-03-03 \u00e0 12.47\" width=\"768\" height=\"576\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/remise-des-prix-de-lexcellence-scolaire-aux-trois-premiers-de-chaque-classe-du-lycee\/\">Remise des prix de l'excellence scolaire aux trois premiers de chaque classe du lyc\u00e9e<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\"><\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/remise-des-prix-de-lexcellence-scolaire-aux-trois-premiers-de-chaque-classe-du-lycee\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/nomination-de-ndi-wamba-severi\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/04\/67d2c0c856d70_1741865160_whatsapp-image-2025-03-03-a-11-54-11-1b6f2786-67d2c0c736b59447971292-768x355.jpg\"  alt=\"67d2c0c856d70_1741865160_whatsapp-image-2025-03-03-a-11-54-11-1b6f2786-67d2c0c736b59447971292\" width=\"768\" height=\"355\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><a href=\"https:\/\/fonakeukeu.org\/en\/category\/communiques\/\">Communiqu\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/nomination-de-ndi-wamba-severi\/\">Nomination de ndi wamba s\u00e9veri<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Nomination de NDI WAMBA S\u00e9verin PDG NDI WAMBA S\u00e9verin PDG des \u00e9tablissements DODO sponsor du match des...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/nomination-de-ndi-wamba-severi\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/celebration-de-la-59eme-edition-de-la-fete-de-la-jeunesse\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-03-03-a-12.47.38_460857ea-768x543.jpg\"  alt=\"WhatsApp Image 2025-03-03 \u00e0 12.47\" width=\"768\" height=\"543\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><a href=\"https:\/\/fonakeukeu.org\/en\/category\/communiques\/\">Communiqu\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/celebration-de-la-59eme-edition-de-la-fete-de-la-jeunesse\/\">C\u00e9l\u00e9bration de la 59\u00e8me \u00e9dition de la f\u00eate de la jeunesse : orientation des jeunes au lyc\u00e9e de Fonakeukeu<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">C\u00e9l\u00e9bration de la f\u00eate de la jeunesse avec d\u00e9fil\u00e9 \u00e0 la chefferie Fonakeukeu\n\n\nDans le cadre de la c\u00e9l\u00e9bration...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/celebration-de-la-59eme-edition-de-la-fete-de-la-jeunesse\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/communique-des-activites-sur-le-programme-de-la-fete-de-la-jeunesse\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-02-05-a-10.21.01_47756c61-768x960.jpg\"  alt=\"WhatsApp Image 2025-02-05 \u00e0 10.21\" width=\"768\" height=\"960\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><a href=\"https:\/\/fonakeukeu.org\/en\/category\/communiques\/\">Communiqu\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/communique-des-activites-sur-le-programme-de-la-fete-de-la-jeunesse\/\">Communiqu\u00e9 des activit\u00e9s sur le programme de la f\u00eate de la jeunesse<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\"><\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/04\/04\/communique-des-activites-sur-le-programme-de-la-fete-de-la-jeunesse\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2025\/03\/03\/communique-a-propos-de-la-fete-de-la-jeunesse\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2025\/03\/E1-768x1024.jpg\"  alt=\"E1\" width=\"768\" height=\"1024\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><a href=\"https:\/\/fonakeukeu.org\/en\/category\/communiques\/\">Communiqu\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2025\/03\/03\/communique-a-propos-de-la-fete-de-la-jeunesse\/\">Communiqu\u00e9 \u00e0 propos de la f\u00eate de la jeunesse<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Bonjour chers responsables et conseillers de l&rsquo;ADF.Afin de nous mettre tous au m\u00eame niveau des...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2025\/03\/03\/communique-a-propos-de-la-fete-de-la-jeunesse\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2024\/07\/26\/programme-des-activites-pour-le-congres-fonakeukeu-concernant-les-enfants-de-moins-de-13-ans-allant-du-jeudi-25-juillet-au-vendredi-26-juillet\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2024\/07\/girl-768x445.jpg\"  alt=\"girl\" width=\"768\" height=\"445\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><a href=\"https:\/\/fonakeukeu.org\/en\/category\/communiques\/\">Communiqu\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2024\/07\/26\/programme-des-activites-pour-le-congres-fonakeukeu-concernant-les-enfants-de-moins-de-13-ans-allant-du-jeudi-25-juillet-au-vendredi-26-juillet\/\">Programme des activit\u00e9s pour le congr\u00e8s Fonakeukeu concernant les enfants de moins de 13 ans, du jeudi 25 juillet au vendredi 26 juillet.<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">allant du jeudi 25 juillet au vendredi 26 juillet.<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2024\/07\/26\/programme-des-activites-pour-le-congres-fonakeukeu-concernant-les-enfants-de-moins-de-13-ans-allant-du-jeudi-25-juillet-au-vendredi-26-juillet\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2023\/10\/10\/bonjour-tout-le-monde\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2023\/07\/322165450_1114924795862977_2152596819298640303_n.jpg\"  alt=\"322165450_1114924795862977_2152596819298640303_n\" width=\"600\" height=\"503\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2023\/10\/10\/bonjour-tout-le-monde\/\">Bonne et Heureuse Ann\u00e9e 2023<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Le Chef Fonakeuke souhaite particuli\u00e8rement \u00e0 sa communaut\u00e9 et \u00e0 tout autre communaut\u00e9 une bonne et heureuse...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2023\/10\/10\/bonjour-tout-le-monde\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2022\/11\/03\/funerailles\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2024\/05\/7-1.jpg\"  alt=\"7 (1)\" width=\"640\" height=\"360\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2022\/11\/03\/funerailles\/\">Fun\u00e9railles<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Les fun\u00e9railles, un adieu empreint d&rsquo;\u00e9motions, honorent, rassemblent et apaisent les vies qui nous...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2022\/11\/03\/funerailles\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2022\/11\/02\/couronnement\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2024\/05\/2-1.jpg\"  alt=\"2 (1)\" width=\"700\" height=\"438\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2022\/11\/02\/couronnement\/\">Couronnement<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Le couronnement, instant solennel o\u00f9 le pouvoir et la responsabilit\u00e9 s&rsquo;entrelacent majestueusement..<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2022\/11\/02\/couronnement\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2022\/11\/01\/danse-traditionnelle\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2024\/05\/1-5.jpg\"  alt=\"1 (5)\" width=\"700\" height=\"438\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2022\/11\/01\/danse-traditionnelle\/\">Danse traditionnelle<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">La danse traditionnelle captive, transmettant l&rsquo;\u00e2me d&rsquo;une culture \u00e0 travers chaque mouvement...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2022\/11\/01\/danse-traditionnelle\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/dalvan-museum-street-art-view-2\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2020\/07\/322064828_1824344367943124_7359232664976708092_n.jpg\"  alt=\"322064828_1824344367943124_7359232664976708092_n\" width=\"720\" height=\"509\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/dalvan-museum-street-art-view-2\/\">Programme Des Fun\u00e9railles De FO'O ZEUFACK 1er et Ses Reines<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">\ud835\udd44\ud835\udd44\ud835\udd3c \ud835\udd3b\ud835\udd3c\ud835\udd4a \ud835\udd3d\ud835\udd4c\u2115\ud835\udd3c\u0301\u211d\ud835\udd38\ud835\udd40\ud835\udd43\ud835\udd43\ud835\udd3c\ud835\udd4a \ud835\udd3b\ud835\udd3c \ud835\udd3d\ud835\udd46&rsquo;\ud835\udd46 \u2124\ud835\udd3c\ud835\udd4c\ud835\udd3d\ud835\udd38\u2102\ud835\udd42 \ud835\udfd9\ud835\udd56\ud835\udd63 \ud835\udd3c\ud835\udd4b \ud835\udd4a\ud835\udd3c\ud835\udd4a \u211d\ud835\udd3c\ud835\udd40\u2115\ud835\udd3c\ud835\udd4a<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/dalvan-museum-street-art-view-2\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/new-australian-economic-culture-2\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2020\/07\/311601158_206203801764261_3036508861201108146_n.jpg\"  alt=\"311601158_206203801764261_3036508861201108146_n\" width=\"720\" height=\"540\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/new-australian-economic-culture-2\/\">N'attendez pas la derni\u00e8re minute pour les bousculades!!!!!<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\"><\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/new-australian-economic-culture-2\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/metro-road-design-plan-2025-2\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2020\/07\/312726820_206164308434877_189928099824705347_n.jpg\"  alt=\"312726820_206164308434877_189928099824705347_n\" width=\"521\" height=\"600\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/metro-road-design-plan-2025-2\/\">Save date du 18 au 28 Janvier 2023<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Ramen graphical user interface stealth. Deployment buyer lean startup network effects mass market\ntechnology...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/metro-road-design-plan-2025-2\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/summer-nights-at-the-library-2\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2020\/07\/15685851650998143025.jpeg\"  alt=\"15685851650998143025\" width=\"500\" height=\"261\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/summer-nights-at-the-library-2\/\">Fonakeukeu, fun\u00e9railles de Fo'o Zeufack 1, les princes et princesses changent la chefferie<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\">Ramen graphical user interface stealth. Deployment buyer lean startup network effects mass market\ntechnology...<\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/summer-nights-at-the-library-2\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/europeon-freedom-fighters-statue\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fonakeukeu.org\/wp-content\/uploads\/2020\/07\/12210295291336586371.jpeg\"  alt=\"12210295291336586371\" width=\"500\" height=\"261\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     <div class=\"ue-grid-item-category\"><a href=\"https:\/\/fonakeukeu.org\/en\/category\/actualites\/\">Actualit\u00e9s<\/a><\/div>\n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/europeon-freedom-fighters-statue\/\">Le Chef Zeufack 2 de Fonakeukeu souhaite que son village devienne un village de 2e d\u00e9gr\u00e9<\/a><\/div>    \n        \n    \n    <div class=\"ue_post_blocks_text\"><\/div>        \t<div class=\"ue_post_blocks_link\">\n          <a class=\"\" href='https:\/\/fonakeukeu.org\/en\/2020\/07\/24\/europeon-freedom-fighters-statue\/'>Lire la suite<\/a>\n    \t<\/div>\n      <\/div>\n<\/div>\n\n<\/div>\n\t\t\t<!-- end Post Blocks -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Actualit\u00e9sCommuniqu\u00e9s Communiqu\u00e9 des activit\u00e9s sur le programme de la f\u00eate de la jeunesse Lire la suite Actualit\u00e9sCommuniqu\u00e9s Communiqu\u00e9 \u00e0 propos de la f\u00eate de la jeunesse Lire la suite Actualit\u00e9sCommuniqu\u00e9s Programme des activit\u00e9s pour le congr\u00e8s Fonakeukeu concernant les enfants de moins de 13 ans, du jeudi 25 juillet au vendredi 26 juillet. allant du [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8715","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/pages\/8715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/comments?post=8715"}],"version-history":[{"count":49,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/pages\/8715\/revisions"}],"predecessor-version":[{"id":9007,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/pages\/8715\/revisions\/9007"}],"wp:attachment":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/media?parent=8715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}