{"id":9229,"date":"2025-09-08T13:41:44","date_gmt":"2025-09-08T11:41:44","guid":{"rendered":"https:\/\/fonakeukeu.org\/?p=9229"},"modified":"2026-02-17T09:19:16","modified_gmt":"2026-02-17T08:19:16","slug":"communique-de-ladf-3","status":"publish","type":"post","link":"https:\/\/fonakeukeu.org\/en\/2025\/09\/08\/communique-de-ladf-3\/","title":{"rendered":"Communiqu\u00e9 de l\u2019adf"},"content":{"rendered":"<p>L\u2019Association pour le D\u00e9veloppement de Fonakeukeu (ADF) informe la communaut\u00e9 \u00e9ducative que les Smart Ladies de Fonakeukeu, engag\u00e9es pour le bien-\u00eatre du village, organisent une C\u00e9r\u00e9monie de l\u2019Excellence Scolaire le vendredi 26 septembre \u00e0 12h, \u00e0 la Maison de la Culture de Fonakeukeu.<\/p><p>Objectif : Valoriser le m\u00e9rite et encourager l\u2019excellence parmi les \u00e9l\u00e8ves et les enseignants des \u00e9coles maternelles, primaires et le Lyc\u00e9e de Fonakeukeu.<\/p><p><strong>R\u00c9COMPENSES AU PROGRAMME :<\/strong><\/p><p>Prix d\u2019encouragement aux meilleurs \u00e9l\u00e8ves de chaque classe<\/p><p>Certificats de reconnaissance aux enseignants distingu\u00e9s<\/p><p>Autres surprises \u00e0 d\u00e9couvrir sur place !<\/p><p>La c\u00e9r\u00e9monie sera suivie d\u2019un moment de convivialit\u00e9 et de dialogue entre les enseignants, leurs chefs d\u2019\u00e9tablissements, et le Chef du village entour\u00e9 de ses notables et \u00e9lites.<\/p><p>La pr\u00e9sence de tous est vivement souhait\u00e9e pour faire de cet \u00e9v\u00e9nement, plac\u00e9 sous le signe du m\u00e9rite et du dialogue, un moment m\u00e9morable.<\/p><p>Pour large diffusion. Le Pr\u00e9sident National de l&rsquo;ADF<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019Association pour le D\u00e9veloppement de Fonakeukeu (ADF) informe la communaut\u00e9 \u00e9ducative que les Smart Ladies de Fonakeukeu, engag\u00e9es pour le bien-\u00eatre du village, organisent une C\u00e9r\u00e9monie de l\u2019Excellence Scolaire le vendredi 26 septembre \u00e0 12h, \u00e0 la Maison de la Culture de Fonakeukeu. Objectif : Valoriser le m\u00e9rite et encourager l\u2019excellence parmi les \u00e9l\u00e8ves et [&hellip;]<\/p>","protected":false},"author":1,"featured_media":7802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[109],"tags":[],"table_tags":[],"class_list":["post-9229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/posts\/9229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/comments?post=9229"}],"version-history":[{"count":1,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/posts\/9229\/revisions"}],"predecessor-version":[{"id":9233,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/posts\/9229\/revisions\/9233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/media\/7802"}],"wp:attachment":[{"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/media?parent=9229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/categories?post=9229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/tags?post=9229"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/fonakeukeu.org\/en\/wp-json\/wp\/v2\/table_tags?post=9229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}